{"id":36090,"date":"2025-09-08T09:10:34","date_gmt":"2025-09-08T09:10:34","guid":{"rendered":"https:\/\/www.arthurholm.com\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/"},"modified":"2025-09-12T08:52:04","modified_gmt":"2025-09-12T08:52:04","slug":"el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus","status":"publish","type":"project","link":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/","title":{"rendered":"El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el centro del nuevo Campus MOL del sur de Budapest -dise\u00f1ado por Foster + Partners como lugar de trabajo sostenible e interconectado del futuro- hay una sala de juntas que demuestra c\u00f3mo la arquitectura y la tecnolog\u00eda pueden integrarse a la perfecci\u00f3n. El elemento central de este espacio es la instalaci\u00f3n de <strong>monitores retr\u00e1ctiles DB2 de Arthur Holm<\/strong>, una soluci\u00f3n elegida no s\u00f3lo por sus prestaciones t\u00e9cnicas, sino tambi\u00e9n por su capacidad para preservar la pureza arquitect\u00f3nica del entorno. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/image001-1024x683.jpg\" alt=\"\" class=\"wp-image-36076\" srcset=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/image001-1024x683.jpg 1024w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/image001-300x200.jpg 300w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/image001-768x512.jpg 768w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/image001-1536x1024.jpg 1536w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/image001.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">La serie DB2 se distingue por su <strong>dise\u00f1o minimalista y su mecanismo patentado<\/strong>, que permite que los monitores desaparezcan completamente dentro de la mesa de la sala de juntas cuando no se utilizan. Esta capacidad era especialmente importante para la sede de MOL, donde el \u00e9nfasis en las l\u00edneas limpias, los materiales naturales y la est\u00e9tica atemporal se extiende a todos los detalles. Al integrar los monitores de forma invisible en la mesa, la tecnolog\u00eda apoya el espacio sin dominarlo visualmente, garantizando que la sala de juntas conserve su sensaci\u00f3n de apertura y elegancia al tiempo que ofrece las \u00faltimas herramientas de colaboraci\u00f3n.  <\/p>\n\n<p class=\"wp-block-paragraph\">El partner h\u00fangaro de Arthur Holm, Streamnet, en consorcio con Visual Europe Group, dise\u00f1\u00f3 espec\u00edficamente para este proyecto un total de <strong>26 monitores retr\u00e1ctiles personalizados de 17 pulgadas<\/strong>. Cada monitor se mejor\u00f3 con <strong>funcionalidad de pantalla t\u00e1ctil<\/strong>, lo que permiti\u00f3 una interacci\u00f3n intuitiva y una colaboraci\u00f3n en tiempo real. Para aumentar a\u00fan m\u00e1s la facilidad de uso, Arthur Holm integr\u00f3 un <strong>sistema de cable USB retr\u00e1ctil motorizado<\/strong> directamente en los monitores, garantizando una conectividad sin fisuras y evitando el desorden. Las unidades tambi\u00e9n incorporan <strong>tres botones capacitivos programables en el cristal frontal<\/strong>, cada uno de ellos acompa\u00f1ado de <strong>indicadores LED de dos colores<\/strong> controlados mediante GPI, que proporcionan una respuesta clara y flexible al usuario.   <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2Share_8-1024x683.jpg\" alt=\"Monitor profesional, motorizado y retr&#xE1;ctil de 17,3&quot; con resoluci&#xF3;n Full HD\" class=\"wp-image-2423\" srcset=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2Share_8-1024x683.jpg 1024w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2Share_8-300x200.jpg 300w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2Share_8-768x512.jpg 768w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2Share_8-1536x1025.jpg 1536w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2Share_8.jpg 1772w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">La integraci\u00f3n exigi\u00f3 una estrecha coordinaci\u00f3n entre el equipo de ingenier\u00eda de Arthur Holm y Streamnet, los dise\u00f1adores de mobiliario y los arquitectos del proyecto. Se prest\u00f3 especial atenci\u00f3n a la sincronizaci\u00f3n de la artesan\u00eda de la mesa de juntas de madera con la mec\u00e1nica de precisi\u00f3n de los monitores. El resultado es un entorno de reuni\u00f3n muy funcional en el que la tecnolog\u00eda avanzada permanece oculta hasta que se necesita, preservando la visi\u00f3n arquitect\u00f3nica y ofreciendo al mismo tiempo un rendimiento s\u00f3lido.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2S_0031-1024x684.jpg\" alt=\"Monitor profesional, motorizado y retr&#xE1;ctil de 17,3&quot; con resoluci&#xF3;n Full HD\" class=\"wp-image-2381\" srcset=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2S_0031-1024x684.jpg 1024w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2S_0031-300x200.jpg 300w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2S_0031-768x513.jpg 768w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2S_0031-1536x1025.jpg 1536w, https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/DB2S_0031-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Esta instalaci\u00f3n ilustra la experiencia de Arthur Holm en la creaci\u00f3n de <strong>soluciones audiovisuales personalizadas, discretas y arquitect\u00f3nicamente alineadas<\/strong>. Los monitores DB2 no s\u00f3lo satisfacen las necesidades funcionales de MOL, sino que tambi\u00e9n encarnan los mismos principios de dise\u00f1o que impulsan todo el proyecto del campus: sostenibilidad, innovaci\u00f3n y armon\u00eda entre las personas, la tecnolog\u00eda y el entorno construido. <\/p>\n\n<p class=\"wp-block-paragraph\">Acerca de <a href=\"https:\/\/www.streamnet.hu\/?lang=en\" target=\"_blank\" rel=\"noreferrer noopener\">Streamnet<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/visualeurope.com\/en\/global\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo Visual Europe<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Productos aplicados a este proyecto:<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.arthurholm.com\/product\/motorized-monitors-db2\/\" target=\"_blank\" rel=\"noreferrer noopener\">DB2<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.arthurholm.com\/es\/ert-30-4\/\">E<\/a><a href=\"https:\/\/www.arthurholm.com\/es\/ert-30-4\/\" target=\"_blank\" rel=\"noreferrer noopener\">RT-30<\/a><\/p>\n","protected":false},"featured_media":36364,"template":"","meta":{"_acf_changed":true},"class_list":["post-36090","project","type-project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus | arthurholm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus | arthurholm\" \/>\n<meta property=\"og:description\" content=\"En el centro del nuevo Campus MOL del sur de Budapest -dise\u00f1ado por Foster + Partners como lugar de trabajo sostenible e interconectado del futuro- hay una sala de juntas que demuestra c\u00f3mo la arquitectura y la tecnolog\u00eda pueden integrarse a la perfecci\u00f3n. El elemento central de este espacio es la instalaci\u00f3n de monitores retr\u00e1ctiles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/\" \/>\n<meta property=\"og:site_name\" content=\"arthurholm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arthurholmscreens\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-12T08:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/Mol_Campus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ArthurHolm1\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/project\\\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/project\\\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\\\/\",\"name\":\"El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus | arthurholm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/project\\\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/project\\\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/MOL1.jpg\",\"datePublished\":\"2025-09-08T09:10:34+00:00\",\"dateModified\":\"2025-09-12T08:52:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/project\\\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/project\\\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/project\\\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/MOL1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/MOL1.jpg\",\"width\":1379,\"height\":1838,\"caption\":\"Custom retractable monitors by Arthur Holm integrated into a sleek wooden table, enhancing collaboration while preserving architectural purity\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/project\\\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/\",\"name\":\"Arthur Holm\",\"description\":\"Soluciones AV invisibles para salas de reuniones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/#organization\"},\"alternateName\":\"Arthur Holm | Monitores Retractiles Motorizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/#organization\",\"name\":\"Arthur Holm\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"width\":155,\"height\":57,\"caption\":\"Arthur Holm\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arthurholmscreens\",\"https:\\\/\\\/x.com\\\/ArthurHolm1\",\"https:\\\/\\\/www.instagram.com\\\/arthur_holm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@arthurholm1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arthur-holm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus | arthurholm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/","og_locale":"es_ES","og_type":"article","og_title":"El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus | arthurholm","og_description":"En el centro del nuevo Campus MOL del sur de Budapest -dise\u00f1ado por Foster + Partners como lugar de trabajo sostenible e interconectado del futuro- hay una sala de juntas que demuestra c\u00f3mo la arquitectura y la tecnolog\u00eda pueden integrarse a la perfecci\u00f3n. El elemento central de este espacio es la instalaci\u00f3n de monitores retr\u00e1ctiles [&hellip;]","og_url":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/","og_site_name":"arthurholm","article_publisher":"https:\/\/www.facebook.com\/arthurholmscreens","article_modified_time":"2025-09-12T08:52:04+00:00","og_image":[{"width":1200,"height":960,"url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/Mol_Campus.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ArthurHolm1","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/","url":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/","name":"El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus | arthurholm","isPartOf":{"@id":"https:\/\/www.arthurholm.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/#primaryimage"},"image":{"@id":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/MOL1.jpg","datePublished":"2025-09-08T09:10:34+00:00","dateModified":"2025-09-12T08:52:04+00:00","breadcrumb":{"@id":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/#primaryimage","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/MOL1.jpg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/09\/MOL1.jpg","width":1379,"height":1838,"caption":"Custom retractable monitors by Arthur Holm integrated into a sleek wooden table, enhancing collaboration while preserving architectural purity"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arthurholm.com\/es\/project\/el-nuevo-edificio-del-campus-mol-es-una-vision-del-lugar-de-trabajo-del-futuro-que-situa-la-sostenibilidad-en-el-centro-del-campus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arthurholm.com\/es\/"},{"@type":"ListItem","position":2,"name":"El nuevo edificio del Campus MOL es una visi\u00f3n del lugar de trabajo del futuro que sit\u00faa la sostenibilidad en el centro del campus"}]},{"@type":"WebSite","@id":"https:\/\/www.arthurholm.com\/es\/#website","url":"https:\/\/www.arthurholm.com\/es\/","name":"Arthur Holm","description":"Soluciones AV invisibles para salas de reuniones","publisher":{"@id":"https:\/\/www.arthurholm.com\/es\/#organization"},"alternateName":"Arthur Holm | Monitores Retractiles Motorizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arthurholm.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arthurholm.com\/es\/#organization","name":"Arthur Holm","url":"https:\/\/www.arthurholm.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arthurholm.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","width":155,"height":57,"caption":"Arthur Holm"},"image":{"@id":"https:\/\/www.arthurholm.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arthurholmscreens","https:\/\/x.com\/ArthurHolm1","https:\/\/www.instagram.com\/arthur_holm\/","https:\/\/www.youtube.com\/@arthurholm1","https:\/\/www.linkedin.com\/company\/arthur-holm"]}]}},"ase":null,"_links":{"self":[{"href":"https:\/\/www.arthurholm.com\/es\/wp-json\/wp\/v2\/project\/36090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arthurholm.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.arthurholm.com\/es\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/es\/wp-json\/wp\/v2\/media\/36364"}],"wp:attachment":[{"href":"https:\/\/www.arthurholm.com\/es\/wp-json\/wp\/v2\/media?parent=36090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}