{"id":10515,"date":"2021-10-27T09:45:20","date_gmt":"2021-10-27T09:45:20","guid":{"rendered":"https:\/\/www.arthurholm.com\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/"},"modified":"2025-05-15T07:56:08","modified_gmt":"2025-05-15T07:56:08","slug":"ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam","status":"publish","type":"project","link":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/","title":{"rendered":"AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2021\/10\/IMG_6615-scaled.jpg\" alt=\"AH2 est un moniteur &#xE9;l&#xE9;gant, tr&#xE8;s facile &#xE0; int&#xE9;grer &#xE0; toute table de r&#xE9;union. Il peut &#xEA;tre rabattu manuellement lorsqu'il n'est pas utilis&#xE9;, ce qui permet d'obtenir une vue nette, propre et rationalis&#xE9;e de l'espace de r&#xE9;union.\"\/><\/p>\n\n<p class=\"wp-block-paragraph\">AH2 est un moniteur \u00e9l\u00e9gant, tr\u00e8s facile \u00e0 int\u00e9grer \u00e0 toute table de r\u00e9union. Il peut \u00eatre rabattu manuellement lorsqu&rsquo;il n&rsquo;est pas utilis\u00e9, ce qui permet d&rsquo;obtenir une vue nette, propre et rationalis\u00e9e de l&rsquo;espace de r\u00e9union. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Les <\/strong>moniteurs pliables manuellement <strong> AH2 sont la solution parfaite pour cr\u00e9er des tables flexibles et polyvalentes qui optimisent l&rsquo;espace disponible. Ces \u00e9crans \u00e9l\u00e9gants favorisent la participation, la cr\u00e9ativit\u00e9 et le travail en \u00e9quipe. Ils se replient facilement, ce qui permet de voir clairement les autres participants ou les \u00e9v\u00e9nements qui se d\u00e9roulent dans la pi\u00e8ce. De plus, l&rsquo;espace r\u00e9duit n\u00e9cessaire \u00e0 l&rsquo;installation permet aux utilisateurs de disposer d&rsquo;une surface de travail sans c\u00e2bles, en utilisant \u00e0 la fois l&rsquo;\u00e9cran et tout autre mat\u00e9riel n\u00e9cessaire sur le bureau. Ou peut-\u00eatre m\u00eame un rangement suppl\u00e9mentaire pour les c\u00e2bles si n\u00e9cessaire (lorsque vous installez le <\/strong> AH2, son rangement pour les c\u00e2bles est cach\u00e9 lorsque le moniteur est repli\u00e9 apr\u00e8s utilisation).   <\/p>\n\n<p class=\"wp-block-paragraph\">Leur position de travail est r\u00e9glable de 110\u00ba \u00e0 une position totalement plate lorsqu&rsquo;ils sont pli\u00e9s sur la surface de la table avec l&rsquo;\u00e9cran vers le bas. Les moniteurs AH2 ont \u00e9t\u00e9 con\u00e7us pour une installation facile sur des meubles standard. <strong><em>pour une installation facile sur du mobilier standard : ils sont compacts, robustes et \u00e9l\u00e9gants.<\/em><\/strong>Ils sont compacts, robustes et \u00e9l\u00e9gants. Ils sont enti\u00e8rement construits en aluminium massif frais\u00e9 avec une finition anodis\u00e9e, y compris un verre antireflet \u00e0 bord noir qui peut \u00eatre tactile.  <\/p>\n\n<p class=\"wp-block-paragraph\">Avec un design discret et classique <strong>AH2 <\/strong>les moniteurs transforment la technologie en un syst\u00e8me attrayant, \u00e0 la pointe du progr\u00e8s, capable de r\u00e9pondre aux normes les plus \u00e9lev\u00e9es tout en offrant une exp\u00e9rience inoubliable \u00e0 l&rsquo;utilisateur.  <\/p>\n","protected":false},"featured_media":10517,"template":"","meta":{"_acf_changed":false},"class_list":["post-10515","project","type-project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM ! | arthurholm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM ! | arthurholm\" \/>\n<meta property=\"og:description\" content=\"AH2 est un moniteur \u00e9l\u00e9gant, tr\u00e8s facile \u00e0 int\u00e9grer \u00e0 toute table de r\u00e9union. Il peut \u00eatre rabattu manuellement lorsqu&rsquo;il n&rsquo;est pas utilis\u00e9, ce qui permet d&rsquo;obtenir une vue nette, propre et rationalis\u00e9e de l&rsquo;espace de r\u00e9union. Les moniteurs pliables manuellement AH2 sont la solution parfaite pour cr\u00e9er des tables flexibles et polyvalentes qui optimisent [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/\" \/>\n<meta property=\"og:site_name\" content=\"arthurholm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arthurholmscreens\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T07:56:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/182025580_528927191855768_238566588067578696_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"761\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ArthurHolm1\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/project\\\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/project\\\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\\\/\",\"name\":\"AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM ! | arthurholm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/project\\\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/project\\\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/182025580_528927191855768_238566588067578696_n.jpg\",\"datePublished\":\"2021-10-27T09:45:20+00:00\",\"dateModified\":\"2025-05-15T07:56:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/project\\\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/project\\\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/project\\\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/182025580_528927191855768_238566588067578696_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/182025580_528927191855768_238566588067578696_n.jpg\",\"width\":1000,\"height\":761,\"caption\":\"Manually foldable AH2 monitors integrated into the boardroom table offer a clean, streamlined workspace with hidden cabling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/project\\\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/\",\"name\":\"Arthur Holm\",\"description\":\"Soluciones AV invisibles para salas de reuniones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/#organization\"},\"alternateName\":\"Arthur Holm | Monitores Retractiles Motorizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/#organization\",\"name\":\"Arthur Holm\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"width\":155,\"height\":57,\"caption\":\"Arthur Holm\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arthurholmscreens\",\"https:\\\/\\\/x.com\\\/ArthurHolm1\",\"https:\\\/\\\/www.instagram.com\\\/arthur_holm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@arthurholm1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arthur-holm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM ! | arthurholm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/","og_locale":"fr_FR","og_type":"article","og_title":"AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM ! | arthurholm","og_description":"AH2 est un moniteur \u00e9l\u00e9gant, tr\u00e8s facile \u00e0 int\u00e9grer \u00e0 toute table de r\u00e9union. Il peut \u00eatre rabattu manuellement lorsqu&rsquo;il n&rsquo;est pas utilis\u00e9, ce qui permet d&rsquo;obtenir une vue nette, propre et rationalis\u00e9e de l&rsquo;espace de r\u00e9union. Les moniteurs pliables manuellement AH2 sont la solution parfaite pour cr\u00e9er des tables flexibles et polyvalentes qui optimisent [&hellip;]","og_url":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/","og_site_name":"arthurholm","article_publisher":"https:\/\/www.facebook.com\/arthurholmscreens","article_modified_time":"2025-05-15T07:56:08+00:00","og_image":[{"width":1000,"height":761,"url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/182025580_528927191855768_238566588067578696_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ArthurHolm1","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/","url":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/","name":"AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM ! | arthurholm","isPartOf":{"@id":"https:\/\/www.arthurholm.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/#primaryimage"},"image":{"@id":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/182025580_528927191855768_238566588067578696_n.jpg","datePublished":"2021-10-27T09:45:20+00:00","dateModified":"2025-05-15T07:56:08+00:00","breadcrumb":{"@id":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/#primaryimage","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/182025580_528927191855768_238566588067578696_n.jpg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/182025580_528927191855768_238566588067578696_n.jpg","width":1000,"height":761,"caption":"Manually foldable AH2 monitors integrated into the boardroom table offer a clean, streamlined workspace with hidden cabling"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arthurholm.com\/fr\/project\/ah2-des-ecrans-pliables-manuellement-dans-la-nouvelle-salle-de-reunion-de-la-cpam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arthurholm.com\/fr\/"},{"@type":"ListItem","position":2,"name":"AH2 des \u00e9crans pliables manuellement dans la nouvelle salle de r\u00e9union de la CPAM !"}]},{"@type":"WebSite","@id":"https:\/\/www.arthurholm.com\/fr\/#website","url":"https:\/\/www.arthurholm.com\/fr\/","name":"Arthur Holm","description":"Soluciones AV invisibles para salas de reuniones","publisher":{"@id":"https:\/\/www.arthurholm.com\/fr\/#organization"},"alternateName":"Arthur Holm | Monitores Retractiles Motorizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arthurholm.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.arthurholm.com\/fr\/#organization","name":"Arthur Holm","url":"https:\/\/www.arthurholm.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.arthurholm.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","width":155,"height":57,"caption":"Arthur Holm"},"image":{"@id":"https:\/\/www.arthurholm.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arthurholmscreens","https:\/\/x.com\/ArthurHolm1","https:\/\/www.instagram.com\/arthur_holm\/","https:\/\/www.youtube.com\/@arthurholm1","https:\/\/www.linkedin.com\/company\/arthur-holm"]}]}},"ase":null,"_links":{"self":[{"href":"https:\/\/www.arthurholm.com\/fr\/wp-json\/wp\/v2\/project\/10515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arthurholm.com\/fr\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.arthurholm.com\/fr\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/fr\/wp-json\/wp\/v2\/media\/10517"}],"wp:attachment":[{"href":"https:\/\/www.arthurholm.com\/fr\/wp-json\/wp\/v2\/media?parent=10515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}