{"id":9011,"date":"2024-12-02T13:55:51","date_gmt":"2024-12-02T11:55:51","guid":{"rendered":"https:\/\/www.arthurholm.com\/monitor-manuali\/"},"modified":"2026-08-13T11:16:34","modified_gmt":"2026-08-13T09:16:34","slug":"monitor-manuali","status":"publish","type":"page","link":"https:\/\/www.arthurholm.com\/it\/monitor-manuali\/","title":{"rendered":"Monitor manuali"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9011\" class=\"elementor elementor-9011 elementor-307\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc3d981 e-con-full e-flex e-con e-parent\" data-id=\"fc3d981\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f580cbd elementor-widget elementor-widget-button\" data-id=\"f580cbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Motorizzato<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e247957 elementor-widget elementor-widget-heading\" data-id=\"e247957\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Manuale<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5fbba6 elementor-widget elementor-widget-button\" data-id=\"a5fbba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/www.arthurholm.com\/it\/monitor-da-parete\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Monitor da parete<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ac8acc e-flex e-con-boxed e-con e-parent\" data-id=\"6ac8acc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3734ab4 e-con-full e-flex e-con e-child\" data-id=\"3734ab4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-127a0c9 elementor-widget elementor-widget-heading\" data-id=\"127a0c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AH1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d96a95f elementor-widget elementor-widget-heading\" data-id=\"d96a95f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Eleganza da tavolo<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63799d5 elementor-widget elementor-widget-button\" data-id=\"63799d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.arthurholm.com\/it\/product\/ah1\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Per saperne di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f16c96 e-con-full e-flex e-con e-child\" data-id=\"0f16c96\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-851b05d elementor-widget elementor-widget-heading\" data-id=\"851b05d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AH2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-737cb5f elementor-widget elementor-widget-heading\" data-id=\"737cb5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ottimizzazione dello spazio<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-103145c elementor-widget elementor-widget-button\" data-id=\"103145c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.arthurholm.com\/it\/product\/ah2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Per saperne di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Motorizzato Manuale Monitor da parete AH1 Eleganza da tavolo Per saperne di pi\u00f9 AH2 Ottimizzazione dello spazio Per saperne di pi\u00f9<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9011","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monitor manuali pensati per spazi eleganti | Arthur Holm<\/title>\n<meta name=\"description\" content=\"Scopri i monitor AV manuali di Arthur Holm: intelligenti, eleganti e poco ingombranti. Esplora la nostra collezione e migliora subito la tua configurazione!\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monitor manuali pensati per spazi eleganti | Arthur Holm\" \/>\n<meta property=\"og:description\" content=\"Scopri i monitor AV manuali di Arthur Holm: intelligenti, eleganti e poco ingombranti. Dai un\u2019occhiata alla nostra collezione e migliora subito la tua configurazione!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arthurholm.com\/it\/monitor-manuali\/\" \/>\n<meta property=\"og:site_name\" content=\"arthurholm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arthurholmscreens\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-13T09:16:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/AH1_-200x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Monitor manuali pensati per spazi eleganti | Arthur Holm\" \/>\n<meta name=\"twitter:description\" content=\"Scopri i monitor AV manuali di Arthur Holm: intelligenti, eleganti e poco ingombranti. Dai un\u2019occhiata alla nostra collezione e migliora subito la tua configurazione!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/AH1_-683x1024.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@ArthurHolm1\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-manuali\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-manuali\\\/\",\"name\":\"Monitor manuali pensati per spazi eleganti | Arthur Holm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#website\"},\"datePublished\":\"2024-12-02T11:55:51+00:00\",\"dateModified\":\"2026-08-13T09:16:34+00:00\",\"description\":\"Scopri i monitor AV manuali di Arthur Holm: intelligenti, eleganti e poco ingombranti. Esplora la nostra collezione e migliora subito la tua configurazione!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-manuali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-manuali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-manuali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monitor manuali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\",\"name\":\"Arthur Holm\",\"description\":\"Soluciones AV invisibles para salas de reuniones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#organization\"},\"alternateName\":\"Arthur Holm | Monitores Retractiles Motorizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#organization\",\"name\":\"Arthur Holm\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"width\":155,\"height\":57,\"caption\":\"Arthur Holm\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arthurholmscreens\",\"https:\\\/\\\/x.com\\\/ArthurHolm1\",\"https:\\\/\\\/www.instagram.com\\\/arthur_holm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@arthurholm1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arthur-holm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monitor manuali pensati per spazi eleganti | Arthur Holm","description":"Scopri i monitor AV manuali di Arthur Holm: intelligenti, eleganti e poco ingombranti. Esplora la nostra collezione e migliora subito la tua configurazione!","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"it_IT","og_type":"article","og_title":"Monitor manuali pensati per spazi eleganti | Arthur Holm","og_description":"Scopri i monitor AV manuali di Arthur Holm: intelligenti, eleganti e poco ingombranti. Dai un\u2019occhiata alla nostra collezione e migliora subito la tua configurazione!","og_url":"https:\/\/www.arthurholm.com\/it\/monitor-manuali\/","og_site_name":"arthurholm","article_publisher":"https:\/\/www.facebook.com\/arthurholmscreens","article_modified_time":"2026-08-13T09:16:34+00:00","og_image":[{"url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/AH1_-200x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Monitor manuali pensati per spazi eleganti | Arthur Holm","twitter_description":"Scopri i monitor AV manuali di Arthur Holm: intelligenti, eleganti e poco ingombranti. Dai un\u2019occhiata alla nostra collezione e migliora subito la tua configurazione!","twitter_image":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/AH1_-683x1024.jpg","twitter_site":"@ArthurHolm1","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arthurholm.com\/it\/monitor-manuali\/","url":"https:\/\/www.arthurholm.com\/it\/monitor-manuali\/","name":"Monitor manuali pensati per spazi eleganti | Arthur Holm","isPartOf":{"@id":"https:\/\/www.arthurholm.com\/it\/#website"},"datePublished":"2024-12-02T11:55:51+00:00","dateModified":"2026-08-13T09:16:34+00:00","description":"Scopri i monitor AV manuali di Arthur Holm: intelligenti, eleganti e poco ingombranti. Esplora la nostra collezione e migliora subito la tua configurazione!","breadcrumb":{"@id":"https:\/\/www.arthurholm.com\/it\/monitor-manuali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arthurholm.com\/it\/monitor-manuali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.arthurholm.com\/it\/monitor-manuali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arthurholm.com\/it\/"},{"@type":"ListItem","position":2,"name":"Monitor manuali"}]},{"@type":"WebSite","@id":"https:\/\/www.arthurholm.com\/it\/#website","url":"https:\/\/www.arthurholm.com\/it\/","name":"Arthur Holm","description":"Soluciones AV invisibles para salas de reuniones","publisher":{"@id":"https:\/\/www.arthurholm.com\/it\/#organization"},"alternateName":"Arthur Holm | Monitores Retractiles Motorizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arthurholm.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.arthurholm.com\/it\/#organization","name":"Arthur Holm","url":"https:\/\/www.arthurholm.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.arthurholm.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","width":155,"height":57,"caption":"Arthur Holm"},"image":{"@id":"https:\/\/www.arthurholm.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arthurholmscreens","https:\/\/x.com\/ArthurHolm1","https:\/\/www.instagram.com\/arthur_holm\/","https:\/\/www.youtube.com\/@arthurholm1","https:\/\/www.linkedin.com\/company\/arthur-holm"]}]}},"ase":null,"_links":{"self":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages\/9011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/comments?post=9011"}],"version-history":[{"count":11,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages\/9011\/revisions"}],"predecessor-version":[{"id":48512,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages\/9011\/revisions\/48512"}],"wp:attachment":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/media?parent=9011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}