{"id":9094,"date":"2025-01-08T09:48:27","date_gmt":"2025-01-08T09:48:27","guid":{"rendered":"https:\/\/www.arthurholm.com\/monitor-motorizzati\/dinamico1\/"},"modified":"2025-03-19T14:05:32","modified_gmt":"2025-03-19T14:05:32","slug":"dinamico1","status":"publish","type":"page","link":"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/","title":{"rendered":"Dinamico1"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9094\" class=\"elementor elementor-9094 elementor-994\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d28192 e-con-full e-flex e-con e-parent\" data-id=\"8d28192\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-368dc92 elementor-widget elementor-widget-heading\" data-id=\"368dc92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Dinamico1<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a3bc34 e-flex e-con-boxed e-con e-parent\" data-id=\"8a3bc34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eac77af e-con-full e-flex e-con e-child\" data-id=\"eac77af\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-69dd341 e-con-full e-flex e-con e-child\" data-id=\"69dd341\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f64d52e elementor-widget elementor-widget-heading\" data-id=\"f64d52e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dynamic1H<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a716607 elementor-widget elementor-widget-heading\" data-id=\"a716607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Senza sforzo e compatto<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d010050 elementor-widget elementor-widget-button\" data-id=\"d010050\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.arthurholm.com\/it\/product\/dynamic1h\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Per saperne di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b8f44b e-flex e-con-boxed e-con e-parent\" data-id=\"6b8f44b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fbfe7ee e-con-full e-flex e-con e-child\" data-id=\"fbfe7ee\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61a2cfe elementor-widget elementor-widget-heading\" data-id=\"61a2cfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DynamicSignatureDisplay<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fedd38 elementor-widget elementor-widget-heading\" data-id=\"5fedd38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Identificazione dell'utente<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b89c3d0 elementor-widget elementor-widget-button\" data-id=\"b89c3d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.arthurholm.com\/it\/product\/dynamicsignaturedisplay\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Per saperne di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c5ecf5 e-con-full e-flex e-con e-child\" data-id=\"4c5ecf5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29a877b elementor-widget elementor-widget-heading\" data-id=\"29a877b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DB1Twin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e862e5 elementor-widget elementor-widget-heading\" data-id=\"4e862e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Comunicazione bidirezionale invisibile<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0cae5 elementor-widget elementor-widget-button\" data-id=\"4e0cae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.arthurholm.com\/it\/product\/db1twin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Per saperne di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dinamico1 Dynamic1H Senza sforzo e compatto Per saperne di pi\u00f9 DynamicSignatureDisplay Identificazione dell&#8217;utente Per saperne di pi\u00f9 DB1Twin Comunicazione bidirezionale invisibile Per saperne di pi\u00f9<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8664,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9094","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dinamico1 | arthurholm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dinamico1 | arthurholm\" \/>\n<meta property=\"og:description\" content=\"Dinamico1 Dynamic1H Senza sforzo e compatto Per saperne di pi\u00f9 DynamicSignatureDisplay Identificazione dell&#8217;utente Per saperne di pi\u00f9 DB1Twin Comunicazione bidirezionale invisibile Per saperne di pi\u00f9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/\" \/>\n<meta property=\"og:site_name\" content=\"arthurholm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arthurholmscreens\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T14:05:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ArthurHolm1\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-motorizzati\\\/dinamico1\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-motorizzati\\\/dinamico1\\\/\",\"name\":\"Dinamico1 | arthurholm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#website\"},\"datePublished\":\"2025-01-08T09:48:27+00:00\",\"dateModified\":\"2025-03-19T14:05:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-motorizzati\\\/dinamico1\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-motorizzati\\\/dinamico1\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-motorizzati\\\/dinamico1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monitor motorizzati\",\"item\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/monitor-motorizzati\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dinamico1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\",\"name\":\"Arthur Holm\",\"description\":\"Soluciones AV invisibles para salas de reuniones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#organization\"},\"alternateName\":\"Arthur Holm | Monitores Retractiles Motorizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#organization\",\"name\":\"Arthur Holm\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"width\":155,\"height\":57,\"caption\":\"Arthur Holm\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arthurholmscreens\",\"https:\\\/\\\/x.com\\\/ArthurHolm1\",\"https:\\\/\\\/www.instagram.com\\\/arthur_holm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@arthurholm1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arthur-holm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dinamico1 | arthurholm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/","og_locale":"it_IT","og_type":"article","og_title":"Dinamico1 | arthurholm","og_description":"Dinamico1 Dynamic1H Senza sforzo e compatto Per saperne di pi\u00f9 DynamicSignatureDisplay Identificazione dell&#8217;utente Per saperne di pi\u00f9 DB1Twin Comunicazione bidirezionale invisibile Per saperne di pi\u00f9","og_url":"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/","og_site_name":"arthurholm","article_publisher":"https:\/\/www.facebook.com\/arthurholmscreens","article_modified_time":"2025-03-19T14:05:32+00:00","twitter_card":"summary_large_image","twitter_site":"@ArthurHolm1","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/","url":"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/","name":"Dinamico1 | arthurholm","isPartOf":{"@id":"https:\/\/www.arthurholm.com\/it\/#website"},"datePublished":"2025-01-08T09:48:27+00:00","dateModified":"2025-03-19T14:05:32+00:00","breadcrumb":{"@id":"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/dinamico1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arthurholm.com\/it\/"},{"@type":"ListItem","position":2,"name":"Monitor motorizzati","item":"https:\/\/www.arthurholm.com\/it\/monitor-motorizzati\/"},{"@type":"ListItem","position":3,"name":"Dinamico1"}]},{"@type":"WebSite","@id":"https:\/\/www.arthurholm.com\/it\/#website","url":"https:\/\/www.arthurholm.com\/it\/","name":"Arthur Holm","description":"Soluciones AV invisibles para salas de reuniones","publisher":{"@id":"https:\/\/www.arthurholm.com\/it\/#organization"},"alternateName":"Arthur Holm | Monitores Retractiles Motorizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arthurholm.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.arthurholm.com\/it\/#organization","name":"Arthur Holm","url":"https:\/\/www.arthurholm.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.arthurholm.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","width":155,"height":57,"caption":"Arthur Holm"},"image":{"@id":"https:\/\/www.arthurholm.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arthurholmscreens","https:\/\/x.com\/ArthurHolm1","https:\/\/www.instagram.com\/arthur_holm\/","https:\/\/www.youtube.com\/@arthurholm1","https:\/\/www.linkedin.com\/company\/arthur-holm"]}]}},"ase":null,"_links":{"self":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages\/9094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/comments?post=9094"}],"version-history":[{"count":2,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages\/9094\/revisions"}],"predecessor-version":[{"id":9100,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages\/9094\/revisions\/9100"}],"up":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/pages\/8664"}],"wp:attachment":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/media?parent=9094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}