{"id":10603,"date":"2025-02-17T13:02:26","date_gmt":"2025-02-17T13:02:26","guid":{"rendered":"https:\/\/www.arthurholm.com\/project\/consiglio-comunale-di-monaco\/"},"modified":"2025-03-24T09:14:34","modified_gmt":"2025-03-24T09:14:34","slug":"consiglio-comunale-di-monaco","status":"publish","type":"project","link":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/","title":{"rendered":"Consiglio Comunale di Monaco"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Il Consiglio Comunale di Monaco sceglie un sottotappeto personalizzato DynamicX2Talk per il suo nuovo municipio<\/h2>\n\n<p class=\"wp-block-paragraph\">Il 14 maggio 2024, il sindaco Georges Marsan, accompagnato dai membri del Consiglio Comunale e dai rappresentanti delle imprese edili monegasche, ha inaugurato con orgoglio la nuova Sala del Consiglio del Municipio di Monaco. Nel suo discorso di apertura, il sindaco Marsan ha sottolineato che questo progetto &#8220;mira a migliorare le condizioni di lavoro e di accoglienza preservando l&#8217;anima di questo luogo&#8221;. Dopo quasi dieci mesi di lavoro meticoloso da parte dei Servizi Tecnici Comunali, ha dichiarato che &#8220;questa doppia ambizione \u00e8 stata pienamente raggiunta&#8221;.  <\/p>\n\n<p class=\"wp-block-paragraph\" style=\"text-transform:uppercase\">M\u00f3naco &#8211; 2024<\/p>\n\n<p class=\"wp-block-paragraph\">Istituzioni, Sale conferenze<\/p>\n\n<p class=\"wp-block-paragraph\">Prodotti: <a href=\"https:\/\/www.arthurholm.com\/product\/motorized-monitor-dynamicx2talk\/\">DynamicX2Talk<\/a><\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/08\/project-dynamicx2talk-2.webp\" alt=\"\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Lo spazio di nuova concezione presenta un design meticoloso che integra armoniosamente il pavimento, la falegnameria, l&#8217;illuminazione e i mobili. Il cuore dello spazio \u00e8 costituito da un tavolo a forma di goccia, realizzato con impiallacciatura di vero rovere affumicato e ornato da una cornice luminosa. Il sindaco Marsan ha sottolineato come questo sia &#8220;un simbolo rafforzato dell&#8217;unit\u00e0 della nostra istituzione&#8221;. Le pareti sono adornate da grandi cornici che mostrano fotografie in bianco e nero di vari siti municipali e dei principali eventi organizzati dal Comune.   <\/p>\n\n<p class=\"wp-block-paragraph\">La nuova Sala del Consiglio \u00e8 dotata di una tecnologia domotica all&#8217;avanguardia che gestisce l&#8217;illuminazione, l&#8217;aria condizionata, il riscaldamento e i sistemi video e audio. Il fulcro di questa modernizzazione sono i 23 schermi motorizzati retrattili UnderCover personalizzati DynamicX2Talk. <\/p>\n\n<p class=\"wp-block-paragraph\">UnderCover \u00e8 una soluzione sofisticata ma semplice che prevede una piastra di copertura automatica sincronizzata con il monitor. Nasconde perfettamente l&#8217;intera gamma di monitor motorizzati a scomparsa verticale di Arthur Holm e altri elementi a scomparsa. Questo meccanismo brevettato permette al monitor, insieme ai microfoni a collo d&#8217;oca per audioconferenza e alle opzioni di connettivit\u00e0 flessibili, di scomparire perfettamente sotto i mobili con la semplice pressione di un pulsante o tramite telecomando.  <\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/08\/project-dynamicx2talk-3.webp\" alt=\"\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Per questo progetto, il sistema UnderCover \u00e8 stato personalizzato per integrare un microfono a collo d&#8217;oca per conferenze, un altoparlante e un connettore HDMI passthrough. Il risultato \u00e8 un&#8217;integrazione intelligente e conveniente che garantisce un aspetto uniforme e snello, migliorando la funzionalit\u00e0 e l&#8217;estetica delle sale riunioni e conferenze. <\/p>\n\n<p class=\"wp-block-paragraph\">I partecipanti alle riunioni possono facilmente visualizzare le presentazioni su un monitor da 17 pollici, utilizzare un microfono a collo d&#8217;oca con pulsante per parlare e collegare ingressi video HDMI. Tutta la tecnologia si integra perfettamente nel tavolo, senza lasciare traccia quando non viene utilizzata. Il meccanismo UnderCover \u00e8 impiallacciato con lo stesso vero rovere affumicato del resto del tavolo, garantendo funzionalit\u00e0, eleganza e discrezione.  <\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/08\/project-dynamicx2talk-4.webp\" alt=\"\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">INS Video cote d&#8217;Azur \u00e8 stata responsabile dell&#8217;integrazione di questo bellissimo progetto che \u00e8 stato completato con Televic, AMX, Shure e Xilica.<\/p>\n\n<p class=\"wp-block-paragraph\">Informazioni su INS: <a href=\"https:\/\/insvideo.fr\/\">https:\/\/insvideo.fr<\/a><\/p>\n","protected":false},"featured_media":10604,"template":"","meta":{"_acf_changed":false},"class_list":["post-10603","project","type-project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consiglio Comunale di Monaco | arthurholm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consiglio Comunale di Monaco | arthurholm\" \/>\n<meta property=\"og:description\" content=\"Il Consiglio Comunale di Monaco sceglie un sottotappeto personalizzato DynamicX2Talk per il suo nuovo municipio Il 14 maggio 2024, il sindaco Georges Marsan, accompagnato dai membri del Consiglio Comunale e dai rappresentanti delle imprese edili monegasche, ha inaugurato con orgoglio la nuova Sala del Consiglio del Municipio di Monaco. Nel suo discorso di apertura, il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/\" \/>\n<meta property=\"og:site_name\" content=\"arthurholm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arthurholmscreens\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T09:14:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/02\/project-dynamicx2talk-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ArthurHolm1\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/consiglio-comunale-di-monaco\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/consiglio-comunale-di-monaco\\\/\",\"name\":\"Consiglio Comunale di Monaco | arthurholm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/consiglio-comunale-di-monaco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/consiglio-comunale-di-monaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/project-dynamicx2talk-1.webp\",\"datePublished\":\"2025-02-17T13:02:26+00:00\",\"dateModified\":\"2025-03-24T09:14:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/consiglio-comunale-di-monaco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/consiglio-comunale-di-monaco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/consiglio-comunale-di-monaco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/project-dynamicx2talk-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/project-dynamicx2talk-1.webp\",\"width\":1920,\"height\":1080,\"caption\":\"Custom UnderCover retractable monitors by Arthur Holm integrated into Monaco\u2019s teardrop-shaped smoked oak table for seamless AV functionality\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/consiglio-comunale-di-monaco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consiglio Comunale di Monaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\",\"name\":\"Arthur Holm\",\"description\":\"Soluciones AV invisibles para salas de reuniones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#organization\"},\"alternateName\":\"Arthur Holm | Monitores Retractiles Motorizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#organization\",\"name\":\"Arthur Holm\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"width\":155,\"height\":57,\"caption\":\"Arthur Holm\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arthurholmscreens\",\"https:\\\/\\\/x.com\\\/ArthurHolm1\",\"https:\\\/\\\/www.instagram.com\\\/arthur_holm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@arthurholm1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arthur-holm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consiglio Comunale di Monaco | arthurholm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/","og_locale":"it_IT","og_type":"article","og_title":"Consiglio Comunale di Monaco | arthurholm","og_description":"Il Consiglio Comunale di Monaco sceglie un sottotappeto personalizzato DynamicX2Talk per il suo nuovo municipio Il 14 maggio 2024, il sindaco Georges Marsan, accompagnato dai membri del Consiglio Comunale e dai rappresentanti delle imprese edili monegasche, ha inaugurato con orgoglio la nuova Sala del Consiglio del Municipio di Monaco. Nel suo discorso di apertura, il [&hellip;]","og_url":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/","og_site_name":"arthurholm","article_publisher":"https:\/\/www.facebook.com\/arthurholmscreens","article_modified_time":"2025-03-24T09:14:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/02\/project-dynamicx2talk-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@ArthurHolm1","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/","url":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/","name":"Consiglio Comunale di Monaco | arthurholm","isPartOf":{"@id":"https:\/\/www.arthurholm.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/#primaryimage"},"image":{"@id":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/02\/project-dynamicx2talk-1.webp","datePublished":"2025-02-17T13:02:26+00:00","dateModified":"2025-03-24T09:14:34+00:00","breadcrumb":{"@id":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/#primaryimage","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/02\/project-dynamicx2talk-1.webp","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/02\/project-dynamicx2talk-1.webp","width":1920,"height":1080,"caption":"Custom UnderCover retractable monitors by Arthur Holm integrated into Monaco\u2019s teardrop-shaped smoked oak table for seamless AV functionality"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arthurholm.com\/it\/project\/consiglio-comunale-di-monaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arthurholm.com\/it\/"},{"@type":"ListItem","position":2,"name":"Consiglio Comunale di Monaco"}]},{"@type":"WebSite","@id":"https:\/\/www.arthurholm.com\/it\/#website","url":"https:\/\/www.arthurholm.com\/it\/","name":"Arthur Holm","description":"Soluciones AV invisibles para salas de reuniones","publisher":{"@id":"https:\/\/www.arthurholm.com\/it\/#organization"},"alternateName":"Arthur Holm | Monitores Retractiles Motorizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arthurholm.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.arthurholm.com\/it\/#organization","name":"Arthur Holm","url":"https:\/\/www.arthurholm.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.arthurholm.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","width":155,"height":57,"caption":"Arthur Holm"},"image":{"@id":"https:\/\/www.arthurholm.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arthurholmscreens","https:\/\/x.com\/ArthurHolm1","https:\/\/www.instagram.com\/arthur_holm\/","https:\/\/www.youtube.com\/@arthurholm1","https:\/\/www.linkedin.com\/company\/arthur-holm"]}]}},"ase":null,"_links":{"self":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/project\/10603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/media\/10604"}],"wp:attachment":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/media?parent=10603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}