{"id":10723,"date":"2019-04-08T14:02:01","date_gmt":"2019-04-08T14:02:01","guid":{"rendered":"https:\/\/www.arthurholm.com\/project\/uffici-della-caixa-bank-a-valencia\/"},"modified":"2025-03-24T09:18:17","modified_gmt":"2025-03-24T09:18:17","slug":"uffici-della-caixa-bank-a-valencia","status":"publish","type":"project","link":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/","title":{"rendered":"Uffici della Caixa Bank a Valencia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La sede centrale di Caixa Bank a Valencia ha scelto gli eleganti monitor AH2 ripiegabili manualmente per la sala riunioni e gli uffici della direzione generale, creando un ambiente di lavoro eccellente in cui il design e la tecnologia rendono le riunioni pi\u00f9 piacevoli ed efficaci.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2019\/04\/CAIXA-BANK-02-e1554731845380.jpg\" alt=\"monitor per le riunioni\"\/><\/figure>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2019\/04\/CAIXA-BANK-09-e1554731864313.jpg\" alt=\"monitor di design per sale riunioni\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\"><strong>Monitor AH2 ripiegabili manualmente<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">AH2 \u00e8 un monitor estremamente elegante con una posizione di lavoro flessibile. Pu\u00f2 essere regolato da 110\u00ba a una posizione completamente ripiegata sul tavolo con lo schermo rivolto verso il basso. <\/p>\n\n<p class=\"wp-block-paragraph\">AH2 \u00e8 stato progettato per una facile installazione su mobili standard con un design compatto ed elegante. Il monitor manuale AH2 \u00e8 interamente costruito in solido alluminio fresato con finitura anodizzata, incluso un vetro nero antiriflesso che pu\u00f2 essere anche un touch screen. AH2 \u00e8 disponibile nei formati 17\u2033 e 22\u2033.  <\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2019\/04\/CAIXA-BANK-13-e1554731962123.jpg\" alt=\"tecnologia collaborativa nelle sale riunioni\"\/><\/figure>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2019\/04\/CAIXA-BANK-12-e1554731881976.jpg\" alt=\"monitor pieghevoli manuali\"\/><\/figure>\n","protected":false},"featured_media":10724,"template":"","meta":{"_acf_changed":false},"class_list":["post-10723","project","type-project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uffici della Caixa Bank a Valencia | arthurholm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uffici della Caixa Bank a Valencia | arthurholm\" \/>\n<meta property=\"og:description\" content=\"La sede centrale di Caixa Bank a Valencia ha scelto gli eleganti monitor AH2 ripiegabili manualmente per la sala riunioni e gli uffici della direzione generale, creando un ambiente di lavoro eccellente in cui il design e la tecnologia rendono le riunioni pi\u00f9 piacevoli ed efficaci. Monitor AH2 ripiegabili manualmente AH2 \u00e8 un monitor estremamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/\" \/>\n<meta property=\"og:site_name\" content=\"arthurholm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arthurholmscreens\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T09:18:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/CaixaBank_AH2-e1554732395515.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1167\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ArthurHolm1\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/uffici-della-caixa-bank-a-valencia\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/uffici-della-caixa-bank-a-valencia\\\/\",\"name\":\"Uffici della Caixa Bank a Valencia | arthurholm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/uffici-della-caixa-bank-a-valencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/uffici-della-caixa-bank-a-valencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/CaixaBank_AH2-e1554732395515.jpg\",\"datePublished\":\"2019-04-08T14:02:01+00:00\",\"dateModified\":\"2025-03-24T09:18:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/uffici-della-caixa-bank-a-valencia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/uffici-della-caixa-bank-a-valencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/uffici-della-caixa-bank-a-valencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/CaixaBank_AH2-e1554732395515.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/CaixaBank_AH2-e1554732395515.jpg\",\"width\":1167,\"height\":465,\"caption\":\"Arthur Holm AH2 manually foldable monitors with sleek aluminum design installed in CaixaBank Valencia offices, enhancing boardroom efficiency and style.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/project\\\/uffici-della-caixa-bank-a-valencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uffici della Caixa Bank a Valencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\",\"name\":\"Arthur Holm\",\"description\":\"Soluciones AV invisibles para salas de reuniones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#organization\"},\"alternateName\":\"Arthur Holm | Monitores Retractiles Motorizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#organization\",\"name\":\"Arthur Holm\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"contentUrl\":\"https:\\\/\\\/www.arthurholm.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AH-LOGO.svg\",\"width\":155,\"height\":57,\"caption\":\"Arthur Holm\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arthurholm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arthurholmscreens\",\"https:\\\/\\\/x.com\\\/ArthurHolm1\",\"https:\\\/\\\/www.instagram.com\\\/arthur_holm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@arthurholm1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arthur-holm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uffici della Caixa Bank a Valencia | arthurholm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/","og_locale":"it_IT","og_type":"article","og_title":"Uffici della Caixa Bank a Valencia | arthurholm","og_description":"La sede centrale di Caixa Bank a Valencia ha scelto gli eleganti monitor AH2 ripiegabili manualmente per la sala riunioni e gli uffici della direzione generale, creando un ambiente di lavoro eccellente in cui il design e la tecnologia rendono le riunioni pi\u00f9 piacevoli ed efficaci. Monitor AH2 ripiegabili manualmente AH2 \u00e8 un monitor estremamente [&hellip;]","og_url":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/","og_site_name":"arthurholm","article_publisher":"https:\/\/www.facebook.com\/arthurholmscreens","article_modified_time":"2025-03-24T09:18:17+00:00","og_image":[{"width":1167,"height":465,"url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/CaixaBank_AH2-e1554732395515.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ArthurHolm1","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/","url":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/","name":"Uffici della Caixa Bank a Valencia | arthurholm","isPartOf":{"@id":"https:\/\/www.arthurholm.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/#primaryimage"},"image":{"@id":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/CaixaBank_AH2-e1554732395515.jpg","datePublished":"2019-04-08T14:02:01+00:00","dateModified":"2025-03-24T09:18:17+00:00","breadcrumb":{"@id":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/#primaryimage","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/CaixaBank_AH2-e1554732395515.jpg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2025\/01\/CaixaBank_AH2-e1554732395515.jpg","width":1167,"height":465,"caption":"Arthur Holm AH2 manually foldable monitors with sleek aluminum design installed in CaixaBank Valencia offices, enhancing boardroom efficiency and style."},{"@type":"BreadcrumbList","@id":"https:\/\/www.arthurholm.com\/it\/project\/uffici-della-caixa-bank-a-valencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arthurholm.com\/it\/"},{"@type":"ListItem","position":2,"name":"Uffici della Caixa Bank a Valencia"}]},{"@type":"WebSite","@id":"https:\/\/www.arthurholm.com\/it\/#website","url":"https:\/\/www.arthurholm.com\/it\/","name":"Arthur Holm","description":"Soluciones AV invisibles para salas de reuniones","publisher":{"@id":"https:\/\/www.arthurholm.com\/it\/#organization"},"alternateName":"Arthur Holm | Monitores Retractiles Motorizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arthurholm.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.arthurholm.com\/it\/#organization","name":"Arthur Holm","url":"https:\/\/www.arthurholm.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.arthurholm.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","contentUrl":"https:\/\/www.arthurholm.com\/wp-content\/uploads\/2024\/11\/AH-LOGO.svg","width":155,"height":57,"caption":"Arthur Holm"},"image":{"@id":"https:\/\/www.arthurholm.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arthurholmscreens","https:\/\/x.com\/ArthurHolm1","https:\/\/www.instagram.com\/arthur_holm\/","https:\/\/www.youtube.com\/@arthurholm1","https:\/\/www.linkedin.com\/company\/arthur-holm"]}]}},"ase":null,"_links":{"self":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/project\/10723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/media\/10724"}],"wp:attachment":[{"href":"https:\/\/www.arthurholm.com\/it\/wp-json\/wp\/v2\/media?parent=10723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}